{"id":5756,"date":"2023-01-01T14:33:49","date_gmt":"2023-01-01T13:33:49","guid":{"rendered":"https:\/\/dajeroma.org\/?p=5756"},"modified":"2023-01-01T14:33:49","modified_gmt":"2023-01-01T13:33:49","slug":"bologna-sinisa-serbia-e-3a-guerra-mondiale","status":"publish","type":"post","link":"https:\/\/dajeroma.org\/en\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/","title":{"rendered":"Bologna: Sinisa, Serbia e 3a guerra mondiale."},"content":{"rendered":"<p class=\"wp-block-paragraph\">Quando si parla del Bologna attuale, \u00e8 doveroso parlare di Sinisa Mihajlovic. Prima mio idolo e poi mio grande avversario, anche come rivale nel derby. Nel tempo, gli ho detto un sacco di parolacce. Impotente davanti alla sua classe, davanti alle sue punizioni precise, violente, maledette. Come allenatore, nel 2019 \u00e8 stato accostato alla Roma e la maggior parte dei romanisti si \u00e8 detta contraria.  Era un grande difensore, centrocampista, terzino, allenatore. Il suo sinistro andrebbe studiato alle pi\u00f9 grandi universit\u00e0. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"187\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2022\/04\/Miha_Bologna.jpeg\" alt=\"\" class=\"wp-image-5180\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2022\/04\/Miha_Bologna.jpeg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2022\/04\/Miha_Bologna-18x12.jpeg 18w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Quando si affacci\u00f2 la leucemia, pregai per lui in modo pubblico. Sperai con lui di averla ricacciata indietro. Infine mi rassegnai come lui all&#8217;inevitabilit\u00e0 della morte. In questa partita, il Bologna giocher\u00e0 soprattutto per lui, ma anche noi dobbiamo mettere in campo il massimo sforzo per onorarlo, per dimostrare che, come lui grande sportivo e combattente avrebbe voluto, non vogliamo regalare la partita, ma portare a casa l&#8217;intera posta. Lui avrebbe voluto cos\u00ec.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quando si parla di Mihajlovic, il mio pensiero vola a Belgrado e alla Serbia. La Serbia \u00e8 una grande nazione. Nella pallavolo, nel basket, nella pallanuoto e nel tennis, con Djokovic, \u00e8 dominante. Sarebbe un terribile peccato escluderla dall&#8217;agone sportivo, se dovesse invadere il Kosovo. Un peccato inevitabile. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"284\" height=\"177\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2022\/03\/Foto_Bandiera.jpg\" alt=\"\" class=\"wp-image-5027\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2022\/03\/Foto_Bandiera.jpg 284w, https:\/\/dajeroma.org\/wp-content\/uploads\/2022\/03\/Foto_Bandiera-18x12.jpg 18w\" sizes=\"auto, (max-width: 284px) 100vw, 284px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Continuo a sperare che i grandi del mondo, anche Russia, Cina, Serbia, Iran, riescano a ragionare sui lati negativi di una guerra mondiale. Siamo alla soglia della terza guerra mondiale con la Cina che si esercita davanti a Taiwan, con la Corea del Nord che lancia missili nel Mar del Giappone, con le tensioni tra Serbia e Kosovo, con la Russia che ha invaso l&#8217;Ucraina e, nonostante abbia difficolt\u00e0 incredibili, non nasconde la sua volont\u00e0 di prolungare ed estendere la guerra ad altri paesi dell&#8217;Est Europa. Spero che questi paesi riescano a capire che la guerra non \u00e8 inevitabile. Siamo ancora in tempo per fermarci e tornare indietro. Semmai ci sar\u00e0 la guerra, io star\u00f2 dalla parte di Taiwan, del Giappone, del Kosovo e delle democrazie dell&#8217;Est Europa. In modo chiaro e netto, sar\u00f2 dalla parte della democrazia e della libert\u00e0. Ma siamo ancora in tempo per fermare questa orrenda macchina. Siamo ancora in tempo per un colloquio alla pari tra Cina e USA. Per il dialogo. Diamo una chance alla pace. Diamo una chance alla pace mondiale.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2022\/04\/bologna.jpg\" alt=\"\" class=\"wp-image-5172\" width=\"401\" height=\"300\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2022\/04\/bologna.jpg 1024w, https:\/\/dajeroma.org\/wp-content\/uploads\/2022\/04\/bologna-300x225.jpg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2022\/04\/bologna-768x576.jpg 768w, https:\/\/dajeroma.org\/wp-content\/uploads\/2022\/04\/bologna-16x12.jpg 16w\" sizes=\"auto, (max-width: 401px) 100vw, 401px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Il Bologna di Thiago Motta \u00e8 una squadra a cui piace offendere. Attaccano dalla destra con Orsolini (mancino), portato ad andare verso il centro per tirare di sinistro, e alla sinistra con il terzino, Cambiaso, con Soriano che ha come posizione prediletta quella pi\u00f9 centrale. Il giocatore pi\u00f9 pericoloso in fase offensiva \u00e8 il centravanti austriaco Arnautovic, bravo con entrambi i piedi.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"478\" height=\"298\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/01\/Bologna_23_1.jpg\" alt=\"\" class=\"wp-image-5760\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/01\/Bologna_23_1.jpg 478w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/01\/Bologna_23_1-300x187.jpg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/01\/Bologna_23_1-18x12.jpg 18w\" sizes=\"auto, (max-width: 478px) 100vw, 478px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Sar\u00e0 difficile prevalere perch\u00e9 loro sono tanto motivati, ma la mia sensazione \u00e8 che per la Roma il peggio \u00e8 passato. Riuscire a sconfiggere il Bologna sarebbe un buon segnale alle avversarie in Serie A, in Europa e soprattutto per noi. Daje Roma!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Giordano Sepi<\/p>","protected":false},"excerpt":{"rendered":"<p>Quando si parla del Bologna attuale, \u00e8 doveroso parlare di Sinisa Mihajlovic. Prima mio idolo e poi mio grande avversario, anche come rivale nel derby. Nel tempo, gli ho detto un sacco di parolacce. Impotente davanti alla sua classe, davanti alle sue punizioni precise, violente, maledette. Come allenatore, nel 2019 \u00e8 stato accostato alla Roma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5760,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,199],"tags":[1572,1573,1575],"class_list":["post-5756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prepartita","category-serie-a","tag-bologna-2022-23","tag-mihajlovic","tag-terza-guerra-mondiale"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bologna: Sinisa, Serbia e 3a guerra mondiale. - Daje Roma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dajeroma.org\/en\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bologna: Sinisa, Serbia e 3a guerra mondiale. - Daje Roma\" \/>\n<meta property=\"og:description\" content=\"Quando si parla del Bologna attuale, \u00e8 doveroso parlare di Sinisa Mihajlovic. Prima mio idolo e poi mio grande avversario, anche come rivale nel derby. Nel tempo, gli ho detto un sacco di parolacce. Impotente davanti alla sua classe, davanti alle sue punizioni precise, violente, maledette. Come allenatore, nel 2019 \u00e8 stato accostato alla Roma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dajeroma.org\/en\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/\" \/>\n<meta property=\"og:site_name\" content=\"Daje Roma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SangueOroAsRoma\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-01T13:33:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/01\/Bologna_23_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"478\" \/>\n\t<meta property=\"og:image:height\" content=\"298\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"loco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GiordanoSepi\" \/>\n<meta name=\"twitter:site\" content=\"@GiordanoSepi\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"loco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/01\\\/01\\\/bologna-sinisa-serbia-e-3a-guerra-mondiale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/01\\\/01\\\/bologna-sinisa-serbia-e-3a-guerra-mondiale\\\/\"},\"author\":{\"name\":\"loco\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/person\\\/6e5e277ed3629273f1b2f76255b5a503\"},\"headline\":\"Bologna: Sinisa, Serbia e 3a guerra mondiale.\",\"datePublished\":\"2023-01-01T13:33:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/01\\\/01\\\/bologna-sinisa-serbia-e-3a-guerra-mondiale\\\/\"},\"wordCount\":489,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/01\\\/01\\\/bologna-sinisa-serbia-e-3a-guerra-mondiale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Bologna_23_1.jpg\",\"keywords\":[\"bologna 2022\\\/23\",\"Mihajlovic\",\"terza guerra mondiale\"],\"articleSection\":[\"prepartita\",\"Serie A\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dajeroma.org\\\/2023\\\/01\\\/01\\\/bologna-sinisa-serbia-e-3a-guerra-mondiale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/01\\\/01\\\/bologna-sinisa-serbia-e-3a-guerra-mondiale\\\/\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/01\\\/01\\\/bologna-sinisa-serbia-e-3a-guerra-mondiale\\\/\",\"name\":\"Bologna: Sinisa, Serbia e 3a guerra mondiale. - Daje Roma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/01\\\/01\\\/bologna-sinisa-serbia-e-3a-guerra-mondiale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/01\\\/01\\\/bologna-sinisa-serbia-e-3a-guerra-mondiale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Bologna_23_1.jpg\",\"datePublished\":\"2023-01-01T13:33:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/01\\\/01\\\/bologna-sinisa-serbia-e-3a-guerra-mondiale\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dajeroma.org\\\/2023\\\/01\\\/01\\\/bologna-sinisa-serbia-e-3a-guerra-mondiale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/01\\\/01\\\/bologna-sinisa-serbia-e-3a-guerra-mondiale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Bologna_23_1.jpg\",\"contentUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Bologna_23_1.jpg\",\"width\":478,\"height\":298},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/01\\\/01\\\/bologna-sinisa-serbia-e-3a-guerra-mondiale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bologna: Sinisa, Serbia e 3a guerra mondiale.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/\",\"name\":\"DajeRoma\",\"description\":\"Se non la sostieni, non chiamarti Romanista!\",\"publisher\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#organization\",\"name\":\"Daje Roma\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/dajeromadaje.jpg\",\"contentUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/dajeromadaje.jpg\",\"width\":1104,\"height\":403,\"caption\":\"Daje Roma\"},\"image\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SangueOroAsRoma\",\"https:\\\/\\\/x.com\\\/GiordanoSepi\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7OuuISCAY3i0wC9HrI0iUA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/person\\\/6e5e277ed3629273f1b2f76255b5a503\",\"name\":\"loco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g\",\"caption\":\"loco\"},\"url\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/author\\\/loco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bologna: Sinisa, Serbia e 3a guerra mondiale. - Daje Roma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dajeroma.org\/en\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/","og_locale":"en_US","og_type":"article","og_title":"Bologna: Sinisa, Serbia e 3a guerra mondiale. - Daje Roma","og_description":"Quando si parla del Bologna attuale, \u00e8 doveroso parlare di Sinisa Mihajlovic. Prima mio idolo e poi mio grande avversario, anche come rivale nel derby. Nel tempo, gli ho detto un sacco di parolacce. Impotente davanti alla sua classe, davanti alle sue punizioni precise, violente, maledette. Come allenatore, nel 2019 \u00e8 stato accostato alla Roma [&hellip;]","og_url":"https:\/\/dajeroma.org\/en\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/","og_site_name":"Daje Roma","article_publisher":"https:\/\/www.facebook.com\/SangueOroAsRoma","article_published_time":"2023-01-01T13:33:49+00:00","og_image":[{"width":478,"height":298,"url":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/01\/Bologna_23_1.jpg","type":"image\/jpeg"}],"author":"loco","twitter_card":"summary_large_image","twitter_creator":"@GiordanoSepi","twitter_site":"@GiordanoSepi","twitter_misc":{"Written by":"loco","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dajeroma.org\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/#article","isPartOf":{"@id":"https:\/\/dajeroma.org\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/"},"author":{"name":"loco","@id":"https:\/\/dajeroma.org\/en\/#\/schema\/person\/6e5e277ed3629273f1b2f76255b5a503"},"headline":"Bologna: Sinisa, Serbia e 3a guerra mondiale.","datePublished":"2023-01-01T13:33:49+00:00","mainEntityOfPage":{"@id":"https:\/\/dajeroma.org\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/"},"wordCount":489,"commentCount":0,"publisher":{"@id":"https:\/\/dajeroma.org\/en\/#organization"},"image":{"@id":"https:\/\/dajeroma.org\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/#primaryimage"},"thumbnailUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/01\/Bologna_23_1.jpg","keywords":["bologna 2022\/23","Mihajlovic","terza guerra mondiale"],"articleSection":["prepartita","Serie A"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dajeroma.org\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dajeroma.org\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/","url":"https:\/\/dajeroma.org\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/","name":"Bologna: Sinisa, Serbia e 3a guerra mondiale. - Daje Roma","isPartOf":{"@id":"https:\/\/dajeroma.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dajeroma.org\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/#primaryimage"},"image":{"@id":"https:\/\/dajeroma.org\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/#primaryimage"},"thumbnailUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/01\/Bologna_23_1.jpg","datePublished":"2023-01-01T13:33:49+00:00","breadcrumb":{"@id":"https:\/\/dajeroma.org\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dajeroma.org\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dajeroma.org\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/#primaryimage","url":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/01\/Bologna_23_1.jpg","contentUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/01\/Bologna_23_1.jpg","width":478,"height":298},{"@type":"BreadcrumbList","@id":"https:\/\/dajeroma.org\/2023\/01\/01\/bologna-sinisa-serbia-e-3a-guerra-mondiale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dajeroma.org\/en\/"},{"@type":"ListItem","position":2,"name":"Bologna: Sinisa, Serbia e 3a guerra mondiale."}]},{"@type":"WebSite","@id":"https:\/\/dajeroma.org\/en\/#website","url":"https:\/\/dajeroma.org\/en\/","name":"DajeRoma","description":"Se non la sostieni, non chiamarti Romanista!","publisher":{"@id":"https:\/\/dajeroma.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dajeroma.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dajeroma.org\/en\/#organization","name":"Daje Roma","url":"https:\/\/dajeroma.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dajeroma.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/dajeroma.org\/wp-content\/uploads\/2017\/03\/dajeromadaje.jpg","contentUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2017\/03\/dajeromadaje.jpg","width":1104,"height":403,"caption":"Daje Roma"},"image":{"@id":"https:\/\/dajeroma.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SangueOroAsRoma","https:\/\/x.com\/GiordanoSepi","https:\/\/www.youtube.com\/channel\/UC7OuuISCAY3i0wC9HrI0iUA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/dajeroma.org\/en\/#\/schema\/person\/6e5e277ed3629273f1b2f76255b5a503","name":"loco","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g","caption":"loco"},"url":"https:\/\/dajeroma.org\/en\/author\/loco\/"}]}},"_links":{"self":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts\/5756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/comments?post=5756"}],"version-history":[{"count":5,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts\/5756\/revisions"}],"predecessor-version":[{"id":5762,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts\/5756\/revisions\/5762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/media\/5760"}],"wp:attachment":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/media?parent=5756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/categories?post=5756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/tags?post=5756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}