{"id":5857,"date":"2023-02-06T11:23:44","date_gmt":"2023-02-06T10:23:44","guid":{"rendered":"https:\/\/dajeroma.org\/?p=5857"},"modified":"2023-02-06T11:23:45","modified_gmt":"2023-02-06T10:23:45","slug":"roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare","status":"publish","type":"post","link":"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/","title":{"rendered":"Roma-Empoli 2-0. Quello scetticismo mascherato da realismo da evitare."},"content":{"rendered":"<p class=\"wp-block-paragraph\">Con l&#8217;Olimpico che non ha ancora finito di cantare la Roma chiude la partita nei primi 6 minuti. E&#8217; meraviglioso vedere l&#8217;Olimpico cantare e dare la carica ai giocatori e i giocatori hanno risposto subito. Per il resto della partita, l&#8217;Empoli ha avuto possesso e territorio senza mai essere pericoloso, mentre i romanisti hanno avuto 3 occasioni in pochi secondi con Zalewski, ElSha e Abraham, su cui Vicario \u00e8 stato incredibile (come da foto di Ermes79 che l&#8217;ha paragonato a Ed Warner, il portiere della Muppets su Holly &amp; Benji). I gol sono arrivati da corners battuti perfettamente da Dybala per la testa di Ibanez (1-0) e Abraham (2-0).<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"453\" height=\"680\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/Empoli_23_1_VicariosuAbrahamcomeHollyeBenji.jpg\" alt=\"\" class=\"wp-image-5858\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/Empoli_23_1_VicariosuAbrahamcomeHollyeBenji.jpg 453w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/Empoli_23_1_VicariosuAbrahamcomeHollyeBenji-200x300.jpg 200w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/Empoli_23_1_VicariosuAbrahamcomeHollyeBenji-8x12.jpg 8w\" sizes=\"auto, (max-width: 453px) 100vw, 453px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Un buon compagno di strada nelle imprese sportive e politiche \u00e8 l&#8217;ottimismo. L&#8217;ottimismo non deve alimentare illusioni, ma allo stesso modo il realismo non deve diventare scetticismo. Questo \u00e8 un discorso valido per la Roma quando diciamo che al momento sarebbe ridicolo parlare di scudetto (con -16 rispetto al Napoli) e non siamo tra i favoriti all&#8217;Europa League (con tante squadre nobili in competizione come Arsenal, Manchester United, Juve e Barcellona tra le altre), ma allo stesso modo dobbiamo puntare pi\u00f9 in alto sia possibile. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un esempio pu\u00f2 essere lo scetticismo con cui la maggior parte degli esperti militari e geopolitici vedevano la guerra in Ucraina all&#8217;inizio, ossia come una facile vittoria della Russia in pochi giorni. Cos\u00ec non \u00e8 stato. E gli ottimisti, come me, si sono dimostrati pi\u00f9 realisti degli scettici che si dicono realisti. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicono &#8220;Cerchiamo di essere realisti&#8221;. Invece il loro catastrofismo ha avuto poco a che fare con la realt\u00e0.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"225\" height=\"225\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2022\/03\/russia_logo_sfondo_bianco.jpg\" alt=\"\" class=\"wp-image-5035\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2022\/03\/russia_logo_sfondo_bianco.jpg 225w, https:\/\/dajeroma.org\/wp-content\/uploads\/2022\/03\/russia_logo_sfondo_bianco-150x150.jpg 150w, https:\/\/dajeroma.org\/wp-content\/uploads\/2022\/03\/russia_logo_sfondo_bianco-12x12.jpg 12w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Questo \u00e8 un discorso valido per un mondo futuro pacifico e democratico. La primavera in Ucraina sar\u00e0 cruciale per il destino del mondo e queste nostre (mi permetto di usare il plurale) aspettative. Se l&#8217;offensiva russa sar\u00e0 respinta dagli ucraini, probabilmente il passo successivo sar\u00e0 un cambiamento della leadership in Russia. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nello scorso articolo avevo parlato di Prigozhyn e Girkin, ma il mio favorito non l&#8217;ho nominato. E&#8217; un personaggio della cerchia di Putin che si \u00e8 sempre dimostrato molto razionale e dialogante con l&#8217;Occidente. Un altro candidato potrebbe essere Medvedev (se \u00e8 ancora vivo), ma parlare ogni due giorni  di nucleare non lo accreditano come un leader razionale. Un nuovo leader in Russia deve coltivare il consenso interno, ma anche l&#8217;amicizia con Europa e Usa (ricordiamo che l&#8217;aquila bicefala zarista ha sempre guardato pi\u00f9 a ovest che a est).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Roma \u00e8 capace nello stesso anno di pareggiare a Bologna e di battere il Barcellona 3-0. Tutti i romanisti sanno quanto \u00e8 folle la Roma. Per\u00f2 se poi chiedi a tutti i tifosi di qualsiasi club, ti diranno la stessa cosa: la mia squadra \u00e8 folle. In realt\u00e0, come ho gi\u00e0 scritto, non \u00e8 folle il club, ma il modo in cui lo amiamo noi, passando dall&#8217;esaltazione, dai voli pindarici di trionfi, al pessimismo leopardiano  e ad uno scetticismo che noi mascheriamo da realismo. Poi c&#8217;\u00e8 la realt\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La realt\u00e0 \u00e8 che \u00e8 normale che un club abbia alti e bassi. Come \u00e8 normale dire che da qui a fine stagione, almeno in Serie A, partiamo favoriti su 16 incontri su 18 (forse escludendo Lazio e Atalanta a Bergamo). L&#8217;importante \u00e8 avere la giusta <strong>TESTA<\/strong> e che le gambe rispondano ai nostri stimoli. Ossia concentrazione e forma fisica. Perch\u00e9, badate bene, la Roma parte favorita anche a Lecce, ma se non si affronta l&#8217;avversario con<strong> seriet\u00e0<\/strong>, il Lecce (ottimo allenatore e alcune ottime individualit\u00e0) ti pu\u00f2 mettere in difficolt\u00e0.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"733\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/commandoultrarulli-1-1024x733.jpg\" alt=\"\" class=\"wp-image-5864\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/commandoultrarulli-1-1024x733.jpg 1024w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/commandoultrarulli-1-300x215.jpg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/commandoultrarulli-1-768x550.jpg 768w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/commandoultrarulli-1-18x12.jpg 18w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/commandoultrarulli-1.jpg 1360w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Eppure il vento soffia ancora,<br>E muove i tuoi riccioli, Roberto.<br>Perch\u00e9 tu non eri solo uno striscione.<br>Eri molto di pi\u00f9.<br>Eri rispettato da tutti gli avversari.<br>I Fedayn come il CUCS era uno dei motivi per cui tanti bimbi divennero romanisti (compreso me).<br>Miti, leggende, eroi omerici.<br>Sabato sei morto un&#8217;altra volta.<br>Colpito alle spalle da un&#8217;infamata.<br>Eppure no. Eppure il vento soffia ancora.<br>Non spetta a me decidere se i Fedayn non debbano esistere pi\u00f9.<br>Non spetta a me se cambiare nome.<br>So che quel gruppo di ragazzi ci sar\u00e0 sempre in Curva Sud.<br>L&#8217;Olimpico non \u00e8 pi\u00f9 quello degli anni &#8217;80, ma ha acquisito tanti giovani tignosi, grintosi con la passione per il giallo ocra e il rosso pompeiano.<br>A te la mia fedelt\u00e0, il mio coraggio, la mia lealt\u00e0 e la mia voce nella gola.<br>Sar\u00e0 l&#8217;ultimo gruppo ad arrendersi ad una sconfitta.<br>Il primo gruppo a intonare il primo coro della partita.<br>E quando l&#8217;inno s&#8217;alzera&#8217;, tutto il mondo tremera&#8217;.<br>E nella tempesta e nella gloria, quei ragazzi, anche quelli con qualche capello bianco, in curva e nel settore ospiti ci sar\u00e0.<br>Certo che non vi arrendete!?<br>Certo che siete proprio Fedayn!<br>Daje Fedayn!<br>Daje Roma!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Giordano Sepi<\/p>","protected":false},"excerpt":{"rendered":"<p>Con l&#8217;Olimpico che non ha ancora finito di cantare la Roma chiude la partita nei primi 6 minuti. E&#8217; meraviglioso vedere l&#8217;Olimpico cantare e dare la carica ai giocatori e i giocatori hanno risposto subito. Per il resto della partita, l&#8217;Empoli ha avuto possesso e territorio senza mai essere pericoloso, mentre i romanisti hanno avuto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5862,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,199],"tags":[1596,1598,1591],"class_list":["post-5857","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prepartita","category-serie-a","tag-empoli-2022-23","tag-leadership-in-russia","tag-ucraina-in-pace"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roma-Empoli 2-0. Quello scetticismo mascherato da realismo da evitare. - Daje Roma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roma-Empoli 2-0. Quello scetticismo mascherato da realismo da evitare. - Daje Roma\" \/>\n<meta property=\"og:description\" content=\"Con l&#8217;Olimpico che non ha ancora finito di cantare la Roma chiude la partita nei primi 6 minuti. E&#8217; meraviglioso vedere l&#8217;Olimpico cantare e dare la carica ai giocatori e i giocatori hanno risposto subito. Per il resto della partita, l&#8217;Empoli ha avuto possesso e territorio senza mai essere pericoloso, mentre i romanisti hanno avuto [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/\" \/>\n<meta property=\"og:site_name\" content=\"Daje Roma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SangueOroAsRoma\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-06T10:23:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-06T10:23:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/commandoultrarulli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"680\" \/>\n\t<meta property=\"og:image:height\" content=\"487\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"loco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GiordanoSepi\" \/>\n<meta name=\"twitter:site\" content=\"@GiordanoSepi\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"loco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/2023\\\/02\\\/06\\\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/2023\\\/02\\\/06\\\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\\\/\"},\"author\":{\"name\":\"loco\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/person\\\/6e5e277ed3629273f1b2f76255b5a503\"},\"headline\":\"Roma-Empoli 2-0. Quello scetticismo mascherato da realismo da evitare.\",\"datePublished\":\"2023-02-06T10:23:44+00:00\",\"dateModified\":\"2023-02-06T10:23:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/2023\\\/02\\\/06\\\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\\\/\"},\"wordCount\":798,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/2023\\\/02\\\/06\\\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/commandoultrarulli.jpg\",\"keywords\":[\"empoli 2022\\\/23\",\"leadership in russia\",\"ucraina in pace\"],\"articleSection\":[\"prepartita\",\"Serie A\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dajeroma.org\\\/en\\\/2023\\\/02\\\/06\\\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/2023\\\/02\\\/06\\\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\\\/\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/2023\\\/02\\\/06\\\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\\\/\",\"name\":\"Roma-Empoli 2-0. Quello scetticismo mascherato da realismo da evitare. - Daje Roma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/2023\\\/02\\\/06\\\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/2023\\\/02\\\/06\\\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/commandoultrarulli.jpg\",\"datePublished\":\"2023-02-06T10:23:44+00:00\",\"dateModified\":\"2023-02-06T10:23:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/2023\\\/02\\\/06\\\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dajeroma.org\\\/en\\\/2023\\\/02\\\/06\\\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/2023\\\/02\\\/06\\\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/commandoultrarulli.jpg\",\"contentUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/commandoultrarulli.jpg\",\"width\":680,\"height\":487},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/2023\\\/02\\\/06\\\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roma-Empoli 2-0. Quello scetticismo mascherato da realismo da evitare.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/\",\"name\":\"DajeRoma\",\"description\":\"Se non la sostieni, non chiamarti Romanista!\",\"publisher\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#organization\",\"name\":\"Daje Roma\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/dajeromadaje.jpg\",\"contentUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/dajeromadaje.jpg\",\"width\":1104,\"height\":403,\"caption\":\"Daje Roma\"},\"image\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SangueOroAsRoma\",\"https:\\\/\\\/x.com\\\/GiordanoSepi\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7OuuISCAY3i0wC9HrI0iUA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/person\\\/6e5e277ed3629273f1b2f76255b5a503\",\"name\":\"loco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g\",\"caption\":\"loco\"},\"url\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/author\\\/loco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roma-Empoli 2-0. Quello scetticismo mascherato da realismo da evitare. - Daje Roma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/","og_locale":"en_US","og_type":"article","og_title":"Roma-Empoli 2-0. Quello scetticismo mascherato da realismo da evitare. - Daje Roma","og_description":"Con l&#8217;Olimpico che non ha ancora finito di cantare la Roma chiude la partita nei primi 6 minuti. E&#8217; meraviglioso vedere l&#8217;Olimpico cantare e dare la carica ai giocatori e i giocatori hanno risposto subito. Per il resto della partita, l&#8217;Empoli ha avuto possesso e territorio senza mai essere pericoloso, mentre i romanisti hanno avuto [&hellip;]","og_url":"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/","og_site_name":"Daje Roma","article_publisher":"https:\/\/www.facebook.com\/SangueOroAsRoma","article_published_time":"2023-02-06T10:23:44+00:00","article_modified_time":"2023-02-06T10:23:45+00:00","og_image":[{"width":680,"height":487,"url":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/commandoultrarulli.jpg","type":"image\/jpeg"}],"author":"loco","twitter_card":"summary_large_image","twitter_creator":"@GiordanoSepi","twitter_site":"@GiordanoSepi","twitter_misc":{"Written by":"loco","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/#article","isPartOf":{"@id":"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/"},"author":{"name":"loco","@id":"https:\/\/dajeroma.org\/en\/#\/schema\/person\/6e5e277ed3629273f1b2f76255b5a503"},"headline":"Roma-Empoli 2-0. Quello scetticismo mascherato da realismo da evitare.","datePublished":"2023-02-06T10:23:44+00:00","dateModified":"2023-02-06T10:23:45+00:00","mainEntityOfPage":{"@id":"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/"},"wordCount":798,"commentCount":0,"publisher":{"@id":"https:\/\/dajeroma.org\/en\/#organization"},"image":{"@id":"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/#primaryimage"},"thumbnailUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/commandoultrarulli.jpg","keywords":["empoli 2022\/23","leadership in russia","ucraina in pace"],"articleSection":["prepartita","Serie A"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/","url":"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/","name":"Roma-Empoli 2-0. Quello scetticismo mascherato da realismo da evitare. - Daje Roma","isPartOf":{"@id":"https:\/\/dajeroma.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/#primaryimage"},"image":{"@id":"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/#primaryimage"},"thumbnailUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/commandoultrarulli.jpg","datePublished":"2023-02-06T10:23:44+00:00","dateModified":"2023-02-06T10:23:45+00:00","breadcrumb":{"@id":"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/#primaryimage","url":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/commandoultrarulli.jpg","contentUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/02\/commandoultrarulli.jpg","width":680,"height":487},{"@type":"BreadcrumbList","@id":"https:\/\/dajeroma.org\/en\/2023\/02\/06\/roma-empoli-2-0-quello-scetticismo-mascherato-da-realismo-da-evitare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dajeroma.org\/en\/"},{"@type":"ListItem","position":2,"name":"Roma-Empoli 2-0. Quello scetticismo mascherato da realismo da evitare."}]},{"@type":"WebSite","@id":"https:\/\/dajeroma.org\/en\/#website","url":"https:\/\/dajeroma.org\/en\/","name":"DajeRoma","description":"Se non la sostieni, non chiamarti Romanista!","publisher":{"@id":"https:\/\/dajeroma.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dajeroma.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dajeroma.org\/en\/#organization","name":"Daje Roma","url":"https:\/\/dajeroma.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dajeroma.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/dajeroma.org\/wp-content\/uploads\/2017\/03\/dajeromadaje.jpg","contentUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2017\/03\/dajeromadaje.jpg","width":1104,"height":403,"caption":"Daje Roma"},"image":{"@id":"https:\/\/dajeroma.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SangueOroAsRoma","https:\/\/x.com\/GiordanoSepi","https:\/\/www.youtube.com\/channel\/UC7OuuISCAY3i0wC9HrI0iUA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/dajeroma.org\/en\/#\/schema\/person\/6e5e277ed3629273f1b2f76255b5a503","name":"loco","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g","caption":"loco"},"url":"https:\/\/dajeroma.org\/en\/author\/loco\/"}]}},"_links":{"self":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts\/5857","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/comments?post=5857"}],"version-history":[{"count":5,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts\/5857\/revisions"}],"predecessor-version":[{"id":5865,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts\/5857\/revisions\/5865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/media\/5862"}],"wp:attachment":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/media?parent=5857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/categories?post=5857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/tags?post=5857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}