{"id":6600,"date":"2023-10-10T16:36:03","date_gmt":"2023-10-10T14:36:03","guid":{"rendered":"https:\/\/dajeroma.org\/?p=6600"},"modified":"2023-10-10T19:01:17","modified_gmt":"2023-10-10T17:01:17","slug":"cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio","status":"publish","type":"post","link":"https:\/\/dajeroma.org\/en\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/","title":{"rendered":"Cagliari-Roma 1-4. Islamico, fratello mio. Ebreo, fratello mio."},"content":{"rendered":"<p class=\"wp-block-paragraph\">La prima partita di Serie A col nuovo sponsor \u00e8 un&#8217;occasione per parlare del sogno di Bin Salman di egemonia culturale, di maggiori diritti in Arabia Saudita e per promuovere il dialogo e la pace tra Israele e Palestina e in generale tra Islam ed Ebraismo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La vittoria con il Cagliari \u00e8 decisiva per ricominciare a vedere la classifica. La Roma ha sbloccato la partita con un ottimo assist di Spina per una bella girata di Houssem Aouar (E a proposito dell&#8217;islamico franco-algerino in questo articolo parleremo a lungo di Islam), ha subito raddoppiato con Lukaku su grandissimo assist di Karsdorp. Poi, nel secondo tempo, ha trovato lo 0-3 con Belotti dopo lancio del bravissimo Paredes e dribbling del Gallo. E&#8217; arrivato lo 0-4 di Lukaku dopo altro grande assist di Leandro e infine \u00e8 arrivato il gol della bandiera del Cagliari con il rigore di Nathan Nandez che, secondo me, non dovrebbe fare l&#8217;esterno, ma il trequartista alla Perrotta dietro le punte. Nathan Nandez mi piace tantissimo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La questione sponsor. Nel nostro blog, ci occupiamo non solo della Roma, ma anche di diritti umani. Viene cos\u00ec naturale parlare di diritti, adesso che la Roma ha chiuso l&#8217;importante accordo con Riyadh Season come sponsor principale. Intanto cos&#8217;\u00e8 il Riyadh Season?<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"383\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/RyadSeasonSponsor.jpeg\" alt=\"\" class=\"wp-image-6608\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/RyadSeasonSponsor.jpeg 680w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/RyadSeasonSponsor-300x169.jpeg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/RyadSeasonSponsor-18x10.jpeg 18w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">E&#8217; un festival di intrattenimento che si svolger\u00e0 nella Capitale araba nell&#8217;autunno 2024. La Roma parteciper\u00e0 anche a due amichevoli nell&#8217;ambito di questa festa. Questo festival fa parte di un disegno mastodontico di Bin Salman, il monarca saudita, di cui fa parte l&#8217;acquisto del Newcastle, il grande rafforzamento di tanti club calcistici arabi, la candidatura all&#8217;EXPO. Quale \u00e8 la motivazione dietro questo grande disegno?<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"652\" height=\"655\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/DonneeIslam.jpg\" alt=\"\" class=\"wp-image-6607\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/DonneeIslam.jpg 652w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/DonneeIslam-300x300.jpg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/DonneeIslam-150x150.jpg 150w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/DonneeIslam-12x12.jpg 12w\" sizes=\"auto, (max-width: 652px) 100vw, 652px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Nel XXIesimo secolo non si domina pi\u00f9 il mondo militarmente, ma culturalmente, ed \u00e8 proprio questo il disegno di Bin Salman: comandare il mondo non lanciando missili e uccidendo persone, ma attraverso il calcio, lo spettacolo, l&#8217;arte. Nel disegno di Bin Salman, l&#8217;Arabia Saudita dovrebbe sostituire l&#8217;Occidente nell&#8217;egemonia culturale del mondo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quello su cui vorrei ragionassero i potenti dell&#8217;Arabia Saudita, compreso Bin Salman, \u00e8 che una monarchia assoluta, una teocrazia in cui esiste la condanna a morte per motivi politici e morali non pu\u00f2 egemonizzare culturalmente l&#8217;Occidente. Dovrebbero imparare dai tifosi del Newcastle che idolatrano Bin Salman allo stadio e poi a casa rispettano le libert\u00e0 della moglie. Senza questo salto sui diritti morali, politici, culturali, in particolare delle donne dell&#8217;Arabia Saudita, \u00e8 impossibile che gli arabi possano dominare culturalmente il mondo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/CastelSantangeloArabiaSauditaMacchinaDonna-1024x576.jpg\" alt=\"\" class=\"wp-image-6609\" style=\"width:750px;height:auto\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/CastelSantangeloArabiaSauditaMacchinaDonna-1024x576.jpg 1024w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/CastelSantangeloArabiaSauditaMacchinaDonna-300x169.jpg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/CastelSantangeloArabiaSauditaMacchinaDonna-768x432.jpg 768w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/CastelSantangeloArabiaSauditaMacchinaDonna-18x10.jpg 18w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/CastelSantangeloArabiaSauditaMacchinaDonna.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le donne in Arabia Saudita hanno iniziato a guidare nel&nbsp;<strong>2018<\/strong>.&nbsp;<a href=\"https:\/\/www.greenme.it\/lifestyle\/costume-e-societa\/donne-guida-arabia-saudita\/\" target=\"_blank\" rel=\"noreferrer noopener\">Il 4 giugno 2018, l\u2019Arabia Saudita ha emesso per la prima volta patenti di guida di cui erano titolari donne saudite<sup>1<\/sup><\/a>.&nbsp;<a href=\"https:\/\/www.ilpost.it\/2018\/06\/24\/arabia-saudita-divieto-guida\/\" target=\"_blank\" rel=\"noreferrer noopener\">Il divieto di guida per le donne \u00e8 stato ufficialmente abolito il&nbsp;<strong>24 giugno 2018<\/strong><sup>2<\/sup><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abbiamo detto che l&#8217;Arabia Saudita \u00e8 una teocrazia. E&#8217; paragonabile al Vaticano per quello che rappresenta per gli islamici di tutto il mondo. E&#8217; cos\u00ec difficile fare riforme in un paese che viene visto come un punto di fermo di principi universali per un miliardo e mezzo di persone. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ma poi la Storia insegna ci\u00f2 che era il califfato in Spagna, unica zona d&#8217;Europa in cui gli ebrei erano veramente liberi. Il Califfato in Spagna si trasform\u00f2 in uno dei precursori dello stato liberale e questo era dovuto dalla libera, naturale, doverosa commistione di culture. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;internazionalizzazione dell&#8217;Arabia Saudita non pu\u00f2 non passare per l&#8217;internazionalizzazione dei diritti in Arabia Saudita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Davanti a questi contenuti, \u00e8 proprio una polemica terra-terra quella dell&#8217;ex-sindaco Virginia Raggi che si \u00e8 lamentata perch\u00e9 la Roma abbia uno sponsor arabo non per un problema di diritti in Arabia, ma per la candidatura all&#8217;EXPO di Riyadh concorrente della citt\u00e0 di Roma. Mi permetto solo di ricordare che la Roma rappresenta Roma attraverso i colori, il nome e il simbolo. Mi scuso con i miei lettori per aver risposto alla bassezza dell&#8217;ex-sindaca.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"432\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/LaGuerrasenzasenso.jpg\" alt=\"\" class=\"wp-image-6606\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/LaGuerrasenzasenso.jpg 680w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/LaGuerrasenzasenso-300x191.jpg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/LaGuerrasenzasenso-18x12.jpg 18w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Parlare dell&#8217;Arabia e del Califfato in Spagna ci aiuta a collegarci alla guerra israelo-palestinese di questi giorni. Dopo il massacro indiscriminato di Hamas, compresi ragazzi che pacificamente partecipavano ad un rave, Israele ha bombardato Gaza, l&#8217;ha cinta d&#8217;assedio, togliendogli cibo, elettricit\u00e0 e acqua e si prepara all&#8217;attacco via terra. Nel frattempo anche a nord si registrano scontri tra Israele ed Hezbollah. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"680\" height=\"383\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/Israele_Bandiera_PalazzoChigi.jpeg\" alt=\"\" class=\"wp-image-6603\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/Israele_Bandiera_PalazzoChigi.jpeg 680w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/Israele_Bandiera_PalazzoChigi-300x169.jpeg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/Israele_Bandiera_PalazzoChigi-18x10.jpeg 18w\" sizes=\"auto, (max-width: 680px) 100vw, 680px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Foto de <a href=\"https:\/\/www.repubblica.it\/\" target=\"_blank\" rel=\"noreferrer noopener\">La Repubblica<\/a> di Palazzo Chigi, sede del Governo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A questo proposito, data la vicinanza degli Hezbollah con l&#8217;Iran, \u00e8 una buona notizia il fatto che l&#8217;Iran abbia escluso la partecipazione all&#8217;attacco. Nemmeno la grande Iran potrebbe nulla contro l&#8217;esercito israeliano, il che poteva forse significare capovolgimenti di potere in Iran con maggiore liberalit\u00e0 per il popolo iraniano, secondo il vecchio adagio &#8220;non tutto il male viene per nuocere&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ma stiamo parlando di fantasie, l&#8217;Iran ha smentito Hamas che dichiarava che l&#8217;Iran era responsabile quanto lei. L&#8217;Iran non vuole partecipare alla crisi. Ci\u00f2 \u00e8 una buona notizia. Rimane il fatto che  sono dalla parte dei giovani iraniani che chiedono maggiore libert\u00e0 e spero che in un futuro ci riescano.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"900\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/Palestina_Manifestazione_Roma.jpeg\" alt=\"\" class=\"wp-image-6604\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/Palestina_Manifestazione_Roma.jpeg 675w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/Palestina_Manifestazione_Roma-225x300.jpeg 225w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/Palestina_Manifestazione_Roma-9x12.jpeg 9w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Foto di <a href=\"https:\/\/contropiano.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">contropiano.org<\/a>, manifestazione a favore della Palestina e della Pace.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fratello mio islamico. Fratello mio ebreo. Per favore, parlate di pace. Mettete in atto tutti gli strumenti per la pace. In particolare mi rivolgo ai pi\u00f9 potenti. Ai governanti di Arabia Saudita, Turchia, Iran, Qatar, Egitto, USA e Russia per mediare per la pace. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il Corano, il Libro Sacro dell&#8217;Islam, ha molti richiami della Bibbia. Forse un giorno Maometto verr\u00e0 riconosciuto dai pi\u00f9 grandi rabbini come un Profeta dell&#8217;Ebraismo. Perch\u00e9 Allah e Jahve sono semplicemente modi diversi di chiamare Dio e nessuno discute che Maometto, per quanto in contatto con Dio, era un essere umano. E allo stesso tempo, <a href=\"https:\/\/www.ioamogesu.com\/cosa-dice-il-corano-riguardo-a-gesu\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nel Corano, Ges\u00f9 Cristo (chiamato &#8216;Isa in arabo) \u00e8 ricordato per la sua nascita miracolosa, i suoi insegnamenti, i miracoli che comp\u00ec per concessione di Dio e la sua vita come rispettato profeta di Dio<sup>1<\/sup><\/a>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Roma ha vinto, ma poi non possiamo non vedere le macerie di Gaza, i giovani israeliani ostaggi, la mancanza di diritti in Arabia e la volont\u00e0 di potenza di Bin Salman. Eppure la vittoria della Roma \u00e8 sempre un buon segno e questo blog continua instancabile a promuovere pace, cultura e diritti in tutto il mondo, come avrebbe continuato a fare mio padre, Mario Sepi, che mor\u00ec proprio 13 anni fa. Daje Roma!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Giordano Sepi<\/p>","protected":false},"excerpt":{"rendered":"<p>La prima partita di Serie A col nuovo sponsor \u00e8 un&#8217;occasione per parlare del sogno di Bin Salman di egemonia culturale, di maggiori diritti in Arabia Saudita e per promuovere il dialogo e la pace tra Israele e Palestina e in generale tra Islam ed Ebraismo. La vittoria con il Cagliari \u00e8 decisiva per ricominciare [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,199],"tags":[],"class_list":["post-6600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-postpartita","category-serie-a"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cagliari-Roma 1-4. Islamico, fratello mio. Ebreo, fratello mio. - Daje Roma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dajeroma.org\/en\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cagliari-Roma 1-4. Islamico, fratello mio. Ebreo, fratello mio. - Daje Roma\" \/>\n<meta property=\"og:description\" content=\"La prima partita di Serie A col nuovo sponsor \u00e8 un&#8217;occasione per parlare del sogno di Bin Salman di egemonia culturale, di maggiori diritti in Arabia Saudita e per promuovere il dialogo e la pace tra Israele e Palestina e in generale tra Islam ed Ebraismo. La vittoria con il Cagliari \u00e8 decisiva per ricominciare [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dajeroma.org\/en\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/\" \/>\n<meta property=\"og:site_name\" content=\"Daje Roma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SangueOroAsRoma\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-10T14:36:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-10T17:01:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/CastelSantangeloArabiaSauditaMacchinaDonna.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"loco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GiordanoSepi\" \/>\n<meta name=\"twitter:site\" content=\"@GiordanoSepi\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"loco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/10\\\/10\\\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/10\\\/10\\\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\\\/\"},\"author\":{\"name\":\"loco\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/person\\\/6e5e277ed3629273f1b2f76255b5a503\"},\"headline\":\"Cagliari-Roma 1-4. Islamico, fratello mio. Ebreo, fratello mio.\",\"datePublished\":\"2023-10-10T14:36:03+00:00\",\"dateModified\":\"2023-10-10T17:01:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/10\\\/10\\\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\\\/\"},\"wordCount\":1066,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/10\\\/10\\\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/CastelSantangeloArabiaSauditaMacchinaDonna.jpg\",\"articleSection\":[\"postpartita\",\"Serie A\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dajeroma.org\\\/2023\\\/10\\\/10\\\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/10\\\/10\\\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\\\/\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/10\\\/10\\\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\\\/\",\"name\":\"Cagliari-Roma 1-4. Islamico, fratello mio. Ebreo, fratello mio. - Daje Roma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/10\\\/10\\\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/10\\\/10\\\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/CastelSantangeloArabiaSauditaMacchinaDonna.jpg\",\"datePublished\":\"2023-10-10T14:36:03+00:00\",\"dateModified\":\"2023-10-10T17:01:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/10\\\/10\\\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dajeroma.org\\\/2023\\\/10\\\/10\\\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/10\\\/10\\\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/CastelSantangeloArabiaSauditaMacchinaDonna.jpg\",\"contentUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/CastelSantangeloArabiaSauditaMacchinaDonna.jpg\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/10\\\/10\\\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cagliari-Roma 1-4. Islamico, fratello mio. Ebreo, fratello mio.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/\",\"name\":\"DajeRoma\",\"description\":\"Se non la sostieni, non chiamarti Romanista!\",\"publisher\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#organization\",\"name\":\"Daje Roma\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/dajeromadaje.jpg\",\"contentUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/dajeromadaje.jpg\",\"width\":1104,\"height\":403,\"caption\":\"Daje Roma\"},\"image\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SangueOroAsRoma\",\"https:\\\/\\\/x.com\\\/GiordanoSepi\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7OuuISCAY3i0wC9HrI0iUA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/person\\\/6e5e277ed3629273f1b2f76255b5a503\",\"name\":\"loco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g\",\"caption\":\"loco\"},\"url\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/author\\\/loco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cagliari-Roma 1-4. Islamico, fratello mio. Ebreo, fratello mio. - Daje Roma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dajeroma.org\/en\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/","og_locale":"en_US","og_type":"article","og_title":"Cagliari-Roma 1-4. Islamico, fratello mio. Ebreo, fratello mio. - Daje Roma","og_description":"La prima partita di Serie A col nuovo sponsor \u00e8 un&#8217;occasione per parlare del sogno di Bin Salman di egemonia culturale, di maggiori diritti in Arabia Saudita e per promuovere il dialogo e la pace tra Israele e Palestina e in generale tra Islam ed Ebraismo. La vittoria con il Cagliari \u00e8 decisiva per ricominciare [&hellip;]","og_url":"https:\/\/dajeroma.org\/en\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/","og_site_name":"Daje Roma","article_publisher":"https:\/\/www.facebook.com\/SangueOroAsRoma","article_published_time":"2023-10-10T14:36:03+00:00","article_modified_time":"2023-10-10T17:01:17+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/CastelSantangeloArabiaSauditaMacchinaDonna.jpg","type":"image\/jpeg"}],"author":"loco","twitter_card":"summary_large_image","twitter_creator":"@GiordanoSepi","twitter_site":"@GiordanoSepi","twitter_misc":{"Written by":"loco","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dajeroma.org\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/#article","isPartOf":{"@id":"https:\/\/dajeroma.org\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/"},"author":{"name":"loco","@id":"https:\/\/dajeroma.org\/en\/#\/schema\/person\/6e5e277ed3629273f1b2f76255b5a503"},"headline":"Cagliari-Roma 1-4. Islamico, fratello mio. Ebreo, fratello mio.","datePublished":"2023-10-10T14:36:03+00:00","dateModified":"2023-10-10T17:01:17+00:00","mainEntityOfPage":{"@id":"https:\/\/dajeroma.org\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/"},"wordCount":1066,"commentCount":0,"publisher":{"@id":"https:\/\/dajeroma.org\/en\/#organization"},"image":{"@id":"https:\/\/dajeroma.org\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/#primaryimage"},"thumbnailUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/CastelSantangeloArabiaSauditaMacchinaDonna.jpg","articleSection":["postpartita","Serie A"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dajeroma.org\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dajeroma.org\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/","url":"https:\/\/dajeroma.org\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/","name":"Cagliari-Roma 1-4. Islamico, fratello mio. Ebreo, fratello mio. - Daje Roma","isPartOf":{"@id":"https:\/\/dajeroma.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dajeroma.org\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/#primaryimage"},"image":{"@id":"https:\/\/dajeroma.org\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/#primaryimage"},"thumbnailUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/CastelSantangeloArabiaSauditaMacchinaDonna.jpg","datePublished":"2023-10-10T14:36:03+00:00","dateModified":"2023-10-10T17:01:17+00:00","breadcrumb":{"@id":"https:\/\/dajeroma.org\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dajeroma.org\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dajeroma.org\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/#primaryimage","url":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/CastelSantangeloArabiaSauditaMacchinaDonna.jpg","contentUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/10\/CastelSantangeloArabiaSauditaMacchinaDonna.jpg","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/dajeroma.org\/2023\/10\/10\/cagliari-roma-1-4-islamico-fratello-mio-ebreo-fratello-mio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dajeroma.org\/en\/"},{"@type":"ListItem","position":2,"name":"Cagliari-Roma 1-4. Islamico, fratello mio. Ebreo, fratello mio."}]},{"@type":"WebSite","@id":"https:\/\/dajeroma.org\/en\/#website","url":"https:\/\/dajeroma.org\/en\/","name":"DajeRoma","description":"Se non la sostieni, non chiamarti Romanista!","publisher":{"@id":"https:\/\/dajeroma.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dajeroma.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dajeroma.org\/en\/#organization","name":"Daje Roma","url":"https:\/\/dajeroma.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dajeroma.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/dajeroma.org\/wp-content\/uploads\/2017\/03\/dajeromadaje.jpg","contentUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2017\/03\/dajeromadaje.jpg","width":1104,"height":403,"caption":"Daje Roma"},"image":{"@id":"https:\/\/dajeroma.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SangueOroAsRoma","https:\/\/x.com\/GiordanoSepi","https:\/\/www.youtube.com\/channel\/UC7OuuISCAY3i0wC9HrI0iUA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/dajeroma.org\/en\/#\/schema\/person\/6e5e277ed3629273f1b2f76255b5a503","name":"loco","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g","caption":"loco"},"url":"https:\/\/dajeroma.org\/en\/author\/loco\/"}]}},"_links":{"self":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts\/6600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/comments?post=6600"}],"version-history":[{"count":4,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts\/6600\/revisions"}],"predecessor-version":[{"id":6614,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts\/6600\/revisions\/6614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/media\/6609"}],"wp:attachment":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/media?parent=6600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/categories?post=6600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/tags?post=6600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}