{"id":6798,"date":"2023-12-19T16:25:24","date_gmt":"2023-12-19T15:25:24","guid":{"rendered":"https:\/\/dajeroma.org\/?p=6798"},"modified":"2023-12-19T17:06:30","modified_gmt":"2023-12-19T16:06:30","slug":"bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo","status":"publish","type":"post","link":"https:\/\/dajeroma.org\/en\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/","title":{"rendered":"Bologna-Roma 2-0. Napoli. Collettivamente. Spirito di squadra. Spirito di mondo."},"content":{"rendered":"<p class=\"wp-block-paragraph\">Leggermente nervose entrambe le squadre, per\u00f2 per il Bologna \u00e8 un buon punto di partenza perch\u00e9 significa applicazione. I gol sono stati di Moro e Ndoye. La chiave della partita \u00e8 stato la loro costruzione che saltava automaticamente il nostro pressing. Perch\u00e9?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fondamentale nel pressing come nella costruzione \u00e8 il movimento. Loro facevano salire anche Calafiori dalla linea difensiva per liberarsi e noi rimanevamo fermi come giocatori del Subbuteo. Se i nostri attaccanti avessero marcato di pi\u00f9 i loro costruttor,i il pressing avrebbe funzionato meglio. Significativo il primo gol, non solo perch\u00e9 Ndoye si libera troppo facilmente di Ndicka, ma anche perch\u00e9 precedentemente Cristante non va a coprire sul movimento senza palla di Freuler.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"478\" height=\"298\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Bologna_2324_1_UscitadalPressing.jpg\" alt=\"\" class=\"wp-image-6805\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Bologna_2324_1_UscitadalPressing.jpg 478w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Bologna_2324_1_UscitadalPressing-300x187.jpg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Bologna_2324_1_UscitadalPressing-18x12.jpg 18w\" sizes=\"auto, (max-width: 478px) 100vw, 478px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ma in generale il pressing per funzionare deve essere collettivo. Deve essere un movimento unico di tutti i 10 giocatori di campo. Domenica non \u00e8 stato cos\u00ec. Mettere quei 5 cos\u00ec dietro \u00e8 una provocazione, ma mi serve per risaltare il fatto che, se vogliamo fare il pressing, anche i difensori devono salire, anche nella met\u00e0 campo avversaria. Senn\u00f2 non lo facciamo e si pu\u00f2 giocare bene lo stesso. Ma il pressing, come la costruzione e mille altre tattiche nel calcio, se non \u00e8 collettivo, non funziona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indipendentemente dal pressing (si possono vincere le partite anche senza), sar\u00e0 fondamentale il gioco di squadra, il collettivo anche col Napoli. Se c&#8217;\u00e8 un aspetto che ha funzionato \u00e8 stata la comunicazione, ma specialmente hanno funzionato quei singoli che fanno del gioco di squadra una forza come Bove.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mazzarri mette il Napoli col solito 433 dello spallettismo, ma con meno possesso, maggiore fase difensiva, maggiore propensione sulle palle contese, pi\u00f9 verticalit\u00e0. Se intendiamo il 433 come schema principalmente offensivo (alla Zeman per intenderci), non abbiamo capito un cazzo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Spesso si mettono in fase difensiva con il 451, anche molto schiacciato in difesa. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Fasedifensivacol451-1024x576.jpeg\" alt=\"\" class=\"wp-image-6799\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Fasedifensivacol451-1024x576.jpeg 1024w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Fasedifensivacol451-300x169.jpeg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Fasedifensivacol451-768x432.jpeg 768w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Fasedifensivacol451-1536x864.jpeg 1536w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Fasedifensivacol451-18x10.jpeg 18w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Fasedifensivacol451.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">In costruzione invece sono abbastanza ortodossi sul 433 e si mettono nello specifico col 4123. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Costruzione4123-1024x576.jpeg\" alt=\"\" class=\"wp-image-6808\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Costruzione4123-1024x576.jpeg 1024w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Costruzione4123-300x169.jpeg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Costruzione4123-768x432.jpeg 768w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Costruzione4123-1536x864.jpeg 1536w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Costruzione4123-18x10.jpeg 18w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Costruzione4123.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Il pressing dell\u2019Inter non gli ha permesso di costruire da dietro. Di solito, orchestra Lobotka, bravissmo anche nel recupero palla, o costruiscono su Kvara, che torna spesso indietro per aiutare la costruzione. O vanno su Di Lorenzo, il terzino destro. O lanciano lungo per Osimhen. Di Lorenzo, il terzino destro, \u00e8 quello che col dribbling porta la palla in attacco e (come si vede dalla foto) si propone di pi\u00f9 in fase offensiva rispetto a Natan. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_AttaccoCentraleMaGuardaDiLorenzoalto-1-1024x576.jpeg\" alt=\"\" class=\"wp-image-6807\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_AttaccoCentraleMaGuardaDiLorenzoalto-1-1024x576.jpeg 1024w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_AttaccoCentraleMaGuardaDiLorenzoalto-1-300x169.jpeg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_AttaccoCentraleMaGuardaDiLorenzoalto-1-768x432.jpeg 768w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_AttaccoCentraleMaGuardaDiLorenzoalto-1-1536x864.jpeg 1536w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_AttaccoCentraleMaGuardaDiLorenzoalto-1-18x10.jpeg 18w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_AttaccoCentraleMaGuardaDiLorenzoalto-1.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Potranno cercare lo spazio tra esterno e braccetto, in particolare sulla loro destra con Anguissa, Politano e sporadicamente anche con Cajuste. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"478\" height=\"298\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Inserimentoadestra.jpg\" alt=\"\" class=\"wp-image-6801\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Inserimentoadestra.jpg 478w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Inserimentoadestra-300x187.jpg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_Inserimentoadestra-18x12.jpg 18w\" sizes=\"auto, (max-width: 478px) 100vw, 478px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Possono difendere a zona sui corner&#8230; <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_CornerDifesaAZona-1024x576.jpeg\" alt=\"\" class=\"wp-image-6802\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_CornerDifesaAZona-1024x576.jpeg 1024w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_CornerDifesaAZona-300x169.jpeg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_CornerDifesaAZona-768x432.jpeg 768w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_CornerDifesaAZona-1536x864.jpeg 1536w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_CornerDifesaAZona-18x10.jpeg 18w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_CornerDifesaAZona.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&#8230; Ma anche a uomo scelta che penso che Mazzarri preferisce.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_CornerDifesaauomo-1024x576.jpeg\" alt=\"\" class=\"wp-image-6803\" srcset=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_CornerDifesaauomo-1024x576.jpeg 1024w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_CornerDifesaauomo-300x169.jpeg 300w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_CornerDifesaauomo-768x432.jpeg 768w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_CornerDifesaauomo-1536x864.jpeg 1536w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_CornerDifesaauomo-18x10.jpeg 18w, https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Napoli_2324_1_CornerDifesaauomo.jpeg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Come \u00e8 fondamentale per la Roma il collettivo, lo spirito di squadra, come ha detto il buon Presidente, Sergio Mattarella, anche il mondo deve agire sulle grandi crisi mondiali collettivamente dalla lotta all&#8217;inquinamento e quindi al cambiamento climatico all&#8217;esplorazione dello spazio, dalla regolamentazione dell&#8217;intelligenza artificiale e della robotica alle guerre in Palestina e Ucraina. Serve uno spirito di mondo. Questa \u00e8 la mia riflessione in questo Natale di guerra e di morte e allo stesso tempo questo Natale deve mettere le basi per i successi della Roma in questa stagione e a lungo termine. Buon Natale romanista!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Giordano Sepi<\/p>","protected":false},"excerpt":{"rendered":"<p>Leggermente nervose entrambe le squadre, per\u00f2 per il Bologna \u00e8 un buon punto di partenza perch\u00e9 significa applicazione. I gol sono stati di Moro e Ndoye. La chiave della partita \u00e8 stato la loro costruzione che saltava automaticamente il nostro pressing. Perch\u00e9? Fondamentale nel pressing come nella costruzione \u00e8 il movimento. Loro facevano salire anche [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6805,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,4,199],"tags":[1695,1696],"class_list":["post-6798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-postpartita","category-prepartita","category-serie-a","tag-bologna-2023-24","tag-napoli-2023-24"],"blocksy_meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bologna-Roma 2-0. Napoli. Collettivamente. Spirito di squadra. Spirito di mondo. - Daje Roma<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dajeroma.org\/en\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bologna-Roma 2-0. Napoli. Collettivamente. Spirito di squadra. Spirito di mondo. - Daje Roma\" \/>\n<meta property=\"og:description\" content=\"Leggermente nervose entrambe le squadre, per\u00f2 per il Bologna \u00e8 un buon punto di partenza perch\u00e9 significa applicazione. I gol sono stati di Moro e Ndoye. La chiave della partita \u00e8 stato la loro costruzione che saltava automaticamente il nostro pressing. Perch\u00e9? Fondamentale nel pressing come nella costruzione \u00e8 il movimento. Loro facevano salire anche [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dajeroma.org\/en\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/\" \/>\n<meta property=\"og:site_name\" content=\"Daje Roma\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SangueOroAsRoma\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-19T15:25:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-19T16:06:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Bologna_2324_1_UscitadalPressing.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"478\" \/>\n\t<meta property=\"og:image:height\" content=\"298\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"loco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GiordanoSepi\" \/>\n<meta name=\"twitter:site\" content=\"@GiordanoSepi\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"loco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/12\\\/19\\\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/12\\\/19\\\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\\\/\"},\"author\":{\"name\":\"loco\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/person\\\/6e5e277ed3629273f1b2f76255b5a503\"},\"headline\":\"Bologna-Roma 2-0. Napoli. Collettivamente. Spirito di squadra. Spirito di mondo.\",\"datePublished\":\"2023-12-19T15:25:24+00:00\",\"dateModified\":\"2023-12-19T16:06:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/12\\\/19\\\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\\\/\"},\"wordCount\":528,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/12\\\/19\\\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Bologna_2324_1_UscitadalPressing.jpg\",\"keywords\":[\"bologna 2023\\\/24\",\"napoli 2023\\\/24\"],\"articleSection\":[\"postpartita\",\"prepartita\",\"Serie A\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dajeroma.org\\\/2023\\\/12\\\/19\\\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/12\\\/19\\\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\\\/\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/12\\\/19\\\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\\\/\",\"name\":\"Bologna-Roma 2-0. Napoli. Collettivamente. Spirito di squadra. Spirito di mondo. - Daje Roma\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/12\\\/19\\\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/12\\\/19\\\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Bologna_2324_1_UscitadalPressing.jpg\",\"datePublished\":\"2023-12-19T15:25:24+00:00\",\"dateModified\":\"2023-12-19T16:06:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/12\\\/19\\\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dajeroma.org\\\/2023\\\/12\\\/19\\\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/12\\\/19\\\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Bologna_2324_1_UscitadalPressing.jpg\",\"contentUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Bologna_2324_1_UscitadalPressing.jpg\",\"width\":478,\"height\":298},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/2023\\\/12\\\/19\\\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bologna-Roma 2-0. Napoli. Collettivamente. Spirito di squadra. Spirito di mondo.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/\",\"name\":\"DajeRoma\",\"description\":\"Se non la sostieni, non chiamarti Romanista!\",\"publisher\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#organization\",\"name\":\"Daje Roma\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/dajeromadaje.jpg\",\"contentUrl\":\"https:\\\/\\\/dajeroma.org\\\/wp-content\\\/uploads\\\/2017\\\/03\\\/dajeromadaje.jpg\",\"width\":1104,\"height\":403,\"caption\":\"Daje Roma\"},\"image\":{\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SangueOroAsRoma\",\"https:\\\/\\\/x.com\\\/GiordanoSepi\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7OuuISCAY3i0wC9HrI0iUA?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/#\\\/schema\\\/person\\\/6e5e277ed3629273f1b2f76255b5a503\",\"name\":\"loco\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g\",\"caption\":\"loco\"},\"url\":\"https:\\\/\\\/dajeroma.org\\\/en\\\/author\\\/loco\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bologna-Roma 2-0. Napoli. Collettivamente. Spirito di squadra. Spirito di mondo. - Daje Roma","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dajeroma.org\/en\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/","og_locale":"en_US","og_type":"article","og_title":"Bologna-Roma 2-0. Napoli. Collettivamente. Spirito di squadra. Spirito di mondo. - Daje Roma","og_description":"Leggermente nervose entrambe le squadre, per\u00f2 per il Bologna \u00e8 un buon punto di partenza perch\u00e9 significa applicazione. I gol sono stati di Moro e Ndoye. La chiave della partita \u00e8 stato la loro costruzione che saltava automaticamente il nostro pressing. Perch\u00e9? Fondamentale nel pressing come nella costruzione \u00e8 il movimento. Loro facevano salire anche [&hellip;]","og_url":"https:\/\/dajeroma.org\/en\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/","og_site_name":"Daje Roma","article_publisher":"https:\/\/www.facebook.com\/SangueOroAsRoma","article_published_time":"2023-12-19T15:25:24+00:00","article_modified_time":"2023-12-19T16:06:30+00:00","og_image":[{"width":478,"height":298,"url":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Bologna_2324_1_UscitadalPressing.jpg","type":"image\/jpeg"}],"author":"loco","twitter_card":"summary_large_image","twitter_creator":"@GiordanoSepi","twitter_site":"@GiordanoSepi","twitter_misc":{"Written by":"loco","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dajeroma.org\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/#article","isPartOf":{"@id":"https:\/\/dajeroma.org\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/"},"author":{"name":"loco","@id":"https:\/\/dajeroma.org\/en\/#\/schema\/person\/6e5e277ed3629273f1b2f76255b5a503"},"headline":"Bologna-Roma 2-0. Napoli. Collettivamente. Spirito di squadra. Spirito di mondo.","datePublished":"2023-12-19T15:25:24+00:00","dateModified":"2023-12-19T16:06:30+00:00","mainEntityOfPage":{"@id":"https:\/\/dajeroma.org\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/"},"wordCount":528,"commentCount":0,"publisher":{"@id":"https:\/\/dajeroma.org\/en\/#organization"},"image":{"@id":"https:\/\/dajeroma.org\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/#primaryimage"},"thumbnailUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Bologna_2324_1_UscitadalPressing.jpg","keywords":["bologna 2023\/24","napoli 2023\/24"],"articleSection":["postpartita","prepartita","Serie A"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dajeroma.org\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/dajeroma.org\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/","url":"https:\/\/dajeroma.org\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/","name":"Bologna-Roma 2-0. Napoli. Collettivamente. Spirito di squadra. Spirito di mondo. - Daje Roma","isPartOf":{"@id":"https:\/\/dajeroma.org\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dajeroma.org\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/#primaryimage"},"image":{"@id":"https:\/\/dajeroma.org\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/#primaryimage"},"thumbnailUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Bologna_2324_1_UscitadalPressing.jpg","datePublished":"2023-12-19T15:25:24+00:00","dateModified":"2023-12-19T16:06:30+00:00","breadcrumb":{"@id":"https:\/\/dajeroma.org\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dajeroma.org\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dajeroma.org\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/#primaryimage","url":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Bologna_2324_1_UscitadalPressing.jpg","contentUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2023\/12\/Bologna_2324_1_UscitadalPressing.jpg","width":478,"height":298},{"@type":"BreadcrumbList","@id":"https:\/\/dajeroma.org\/2023\/12\/19\/bologna-roma-2-0-napoli-collettivamente-spirito-di-squadra-spirito-di-mondo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dajeroma.org\/en\/"},{"@type":"ListItem","position":2,"name":"Bologna-Roma 2-0. Napoli. Collettivamente. Spirito di squadra. Spirito di mondo."}]},{"@type":"WebSite","@id":"https:\/\/dajeroma.org\/en\/#website","url":"https:\/\/dajeroma.org\/en\/","name":"DajeRoma","description":"Se non la sostieni, non chiamarti Romanista!","publisher":{"@id":"https:\/\/dajeroma.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dajeroma.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dajeroma.org\/en\/#organization","name":"Daje Roma","url":"https:\/\/dajeroma.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dajeroma.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/dajeroma.org\/wp-content\/uploads\/2017\/03\/dajeromadaje.jpg","contentUrl":"https:\/\/dajeroma.org\/wp-content\/uploads\/2017\/03\/dajeromadaje.jpg","width":1104,"height":403,"caption":"Daje Roma"},"image":{"@id":"https:\/\/dajeroma.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SangueOroAsRoma","https:\/\/x.com\/GiordanoSepi","https:\/\/www.youtube.com\/channel\/UC7OuuISCAY3i0wC9HrI0iUA?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/dajeroma.org\/en\/#\/schema\/person\/6e5e277ed3629273f1b2f76255b5a503","name":"loco","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/72396e0bc5149cb51c227a802fbf4dd424600ffe126a0ae3293206a7ad5ddadc?s=96&d=mm&r=g","caption":"loco"},"url":"https:\/\/dajeroma.org\/en\/author\/loco\/"}]}},"_links":{"self":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts\/6798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/comments?post=6798"}],"version-history":[{"count":5,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts\/6798\/revisions"}],"predecessor-version":[{"id":6811,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/posts\/6798\/revisions\/6811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/media\/6805"}],"wp:attachment":[{"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/media?parent=6798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/categories?post=6798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dajeroma.org\/en\/wp-json\/wp\/v2\/tags?post=6798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}